{"id":11386,"date":"2020-03-28T15:52:10","date_gmt":"2020-03-28T15:52:10","guid":{"rendered":"https:\/\/www.fundaciomascort.com\/press\/peces-escollides-a-torroella-el-punt-avui\/"},"modified":"2020-03-28T15:52:10","modified_gmt":"2020-03-28T15:52:10","slug":"peces-escollides-a-torroella-el-punt-avui","status":"publish","type":"press","link":"https:\/\/www.fundaciomascort.com\/es\/prensa\/peces-escollides-a-torroella-el-punt-avui\/","title":{"rendered":"Peces escollides a Torroella, El Punt Avui &#8211;"},"template":"","class_list":["post-11386","press","type-press","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Peces escollides a Torroella, El Punt Avui - Fundaci\u00f3 Mascort<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fundaciomascort.com\/es\/prensa\/peces-escollides-a-torroella-el-punt-avui\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peces escollides a Torroella, El Punt Avui - Fundaci\u00f3 Mascort\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fundaciomascort.com\/es\/prensa\/peces-escollides-a-torroella-el-punt-avui\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3 Mascort\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fundaciomascort\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@fundaciomascort\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fundaciomascort.com\/es\/prensa\/peces-escollides-a-torroella-el-punt-avui\/\",\"url\":\"https:\/\/www.fundaciomascort.com\/es\/prensa\/peces-escollides-a-torroella-el-punt-avui\/\",\"name\":\"Peces escollides a Torroella, El Punt Avui - Fundaci\u00f3 Mascort\",\"isPartOf\":{\"@id\":\"https:\/\/www.fundaciomascort.com\/es\/#website\"},\"datePublished\":\"2020-03-28T15:52:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fundaciomascort.com\/es\/prensa\/peces-escollides-a-torroella-el-punt-avui\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fundaciomascort.com\/es\/prensa\/peces-escollides-a-torroella-el-punt-avui\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fundaciomascort.com\/es\/prensa\/peces-escollides-a-torroella-el-punt-avui\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fundaciomascort.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prensa\",\"item\":\"https:\/\/www.fundaciomascort.com\/es\/prensa\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Peces escollides a Torroella, El Punt Avui &#8211;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fundaciomascort.com\/es\/#website\",\"url\":\"https:\/\/www.fundaciomascort.com\/es\/\",\"name\":\"Fundaci\u00f3 Mascort\",\"description\":\"Esperem que compartiu amb nosaltres les exposicions de la Casa Galibern i les nostres publicacions.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fundaciomascort.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peces escollides a Torroella, El Punt Avui - Fundaci\u00f3 Mascort","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fundaciomascort.com\/es\/prensa\/peces-escollides-a-torroella-el-punt-avui\/","og_locale":"es_ES","og_type":"article","og_title":"Peces escollides a Torroella, El Punt Avui - Fundaci\u00f3 Mascort","og_url":"https:\/\/www.fundaciomascort.com\/es\/prensa\/peces-escollides-a-torroella-el-punt-avui\/","og_site_name":"Fundaci\u00f3 Mascort","article_publisher":"https:\/\/www.facebook.com\/fundaciomascort","twitter_card":"summary_large_image","twitter_site":"@fundaciomascort","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fundaciomascort.com\/es\/prensa\/peces-escollides-a-torroella-el-punt-avui\/","url":"https:\/\/www.fundaciomascort.com\/es\/prensa\/peces-escollides-a-torroella-el-punt-avui\/","name":"Peces escollides a Torroella, El Punt Avui - Fundaci\u00f3 Mascort","isPartOf":{"@id":"https:\/\/www.fundaciomascort.com\/es\/#website"},"datePublished":"2020-03-28T15:52:10+00:00","breadcrumb":{"@id":"https:\/\/www.fundaciomascort.com\/es\/prensa\/peces-escollides-a-torroella-el-punt-avui\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fundaciomascort.com\/es\/prensa\/peces-escollides-a-torroella-el-punt-avui\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fundaciomascort.com\/es\/prensa\/peces-escollides-a-torroella-el-punt-avui\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fundaciomascort.com\/es\/"},{"@type":"ListItem","position":2,"name":"Prensa","item":"https:\/\/www.fundaciomascort.com\/es\/prensa\/"},{"@type":"ListItem","position":3,"name":"Peces escollides a Torroella, El Punt Avui &#8211;"}]},{"@type":"WebSite","@id":"https:\/\/www.fundaciomascort.com\/es\/#website","url":"https:\/\/www.fundaciomascort.com\/es\/","name":"Fundaci\u00f3 Mascort","description":"Esperem que compartiu amb nosaltres les exposicions de la Casa Galibern i les nostres publicacions.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fundaciomascort.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.fundaciomascort.com\/es\/wp-json\/wp\/v2\/press\/11386"}],"collection":[{"href":"https:\/\/www.fundaciomascort.com\/es\/wp-json\/wp\/v2\/press"}],"about":[{"href":"https:\/\/www.fundaciomascort.com\/es\/wp-json\/wp\/v2\/types\/press"}],"wp:attachment":[{"href":"https:\/\/www.fundaciomascort.com\/es\/wp-json\/wp\/v2\/media?parent=11386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}