{"id":11227,"date":"2020-03-28T16:39:38","date_gmt":"2020-03-28T16:39:38","guid":{"rendered":"https:\/\/www.fundaciomascort.com\/press\/una-nova-joia-de-la-fundacio-mascort-top-girona\/"},"modified":"2020-05-01T10:36:11","modified_gmt":"2020-05-01T10:36:11","slug":"una-nova-joia-de-la-fundacio-mascort-top-girona","status":"publish","type":"press","link":"https:\/\/www.fundaciomascort.com\/en\/press\/una-nova-joia-de-la-fundacio-mascort-top-girona\/","title":{"rendered":"Una nova joia de la Fundaci\u00f3 Mascort, Top Girona &#8211;"},"template":"","class_list":["post-11227","press","type-press","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una nova joia de la Fundaci\u00f3 Mascort, Top Girona - Fundaci\u00f3 Mascort<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fundaciomascort.com\/en\/press\/una-nova-joia-de-la-fundacio-mascort-top-girona\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una nova joia de la Fundaci\u00f3 Mascort, Top Girona - Fundaci\u00f3 Mascort\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fundaciomascort.com\/en\/press\/una-nova-joia-de-la-fundacio-mascort-top-girona\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3 Mascort\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fundaciomascort\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-01T10:36:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@fundaciomascort\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fundaciomascort.com\/en\/press\/una-nova-joia-de-la-fundacio-mascort-top-girona\/\",\"url\":\"https:\/\/www.fundaciomascort.com\/en\/press\/una-nova-joia-de-la-fundacio-mascort-top-girona\/\",\"name\":\"Una nova joia de la Fundaci\u00f3 Mascort, Top Girona - Fundaci\u00f3 Mascort\",\"isPartOf\":{\"@id\":\"https:\/\/www.fundaciomascort.com\/en\/#website\"},\"datePublished\":\"2020-03-28T16:39:38+00:00\",\"dateModified\":\"2020-05-01T10:36:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fundaciomascort.com\/en\/press\/una-nova-joia-de-la-fundacio-mascort-top-girona\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fundaciomascort.com\/en\/press\/una-nova-joia-de-la-fundacio-mascort-top-girona\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fundaciomascort.com\/en\/press\/una-nova-joia-de-la-fundacio-mascort-top-girona\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fundaciomascort.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Press\",\"item\":\"https:\/\/www.fundaciomascort.com\/en\/press\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Una nova joia de la Fundaci\u00f3 Mascort, Top Girona &#8211;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fundaciomascort.com\/en\/#website\",\"url\":\"https:\/\/www.fundaciomascort.com\/en\/\",\"name\":\"Fundaci\u00f3 Mascort\",\"description\":\"Esperem que compartiu amb nosaltres les exposicions de la Casa Galibern i les nostres publicacions.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fundaciomascort.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una nova joia de la Fundaci\u00f3 Mascort, Top Girona - Fundaci\u00f3 Mascort","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fundaciomascort.com\/en\/press\/una-nova-joia-de-la-fundacio-mascort-top-girona\/","og_locale":"en_US","og_type":"article","og_title":"Una nova joia de la Fundaci\u00f3 Mascort, Top Girona - Fundaci\u00f3 Mascort","og_url":"https:\/\/www.fundaciomascort.com\/en\/press\/una-nova-joia-de-la-fundacio-mascort-top-girona\/","og_site_name":"Fundaci\u00f3 Mascort","article_publisher":"https:\/\/www.facebook.com\/fundaciomascort","article_modified_time":"2020-05-01T10:36:11+00:00","twitter_card":"summary_large_image","twitter_site":"@fundaciomascort","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fundaciomascort.com\/en\/press\/una-nova-joia-de-la-fundacio-mascort-top-girona\/","url":"https:\/\/www.fundaciomascort.com\/en\/press\/una-nova-joia-de-la-fundacio-mascort-top-girona\/","name":"Una nova joia de la Fundaci\u00f3 Mascort, Top Girona - Fundaci\u00f3 Mascort","isPartOf":{"@id":"https:\/\/www.fundaciomascort.com\/en\/#website"},"datePublished":"2020-03-28T16:39:38+00:00","dateModified":"2020-05-01T10:36:11+00:00","breadcrumb":{"@id":"https:\/\/www.fundaciomascort.com\/en\/press\/una-nova-joia-de-la-fundacio-mascort-top-girona\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fundaciomascort.com\/en\/press\/una-nova-joia-de-la-fundacio-mascort-top-girona\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fundaciomascort.com\/en\/press\/una-nova-joia-de-la-fundacio-mascort-top-girona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fundaciomascort.com\/en\/"},{"@type":"ListItem","position":2,"name":"Press","item":"https:\/\/www.fundaciomascort.com\/en\/press\/"},{"@type":"ListItem","position":3,"name":"Una nova joia de la Fundaci\u00f3 Mascort, Top Girona &#8211;"}]},{"@type":"WebSite","@id":"https:\/\/www.fundaciomascort.com\/en\/#website","url":"https:\/\/www.fundaciomascort.com\/en\/","name":"Fundaci\u00f3 Mascort","description":"Esperem que compartiu amb nosaltres les exposicions de la Casa Galibern i les nostres publicacions.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fundaciomascort.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.fundaciomascort.com\/en\/wp-json\/wp\/v2\/press\/11227"}],"collection":[{"href":"https:\/\/www.fundaciomascort.com\/en\/wp-json\/wp\/v2\/press"}],"about":[{"href":"https:\/\/www.fundaciomascort.com\/en\/wp-json\/wp\/v2\/types\/press"}],"wp:attachment":[{"href":"https:\/\/www.fundaciomascort.com\/en\/wp-json\/wp\/v2\/media?parent=11227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}